{"id":2666,"date":"2016-10-26T07:00:05","date_gmt":"2016-10-26T07:00:05","guid":{"rendered":"https:\/\/sgan.es\/?p=2666"},"modified":"2016-11-02T11:41:58","modified_gmt":"2016-11-02T11:41:58","slug":"ix-reunion-nacional-de-dialisis-peritoneal","status":"publish","type":"post","link":"https:\/\/sgan.es\/gl\/events-list-1\/ix-reunion-nacional-de-dialisis-peritoneal\/","title":{"rendered":"IX Reuni\u00f3n Nacional de Di\u00e1lisis Peritoneal"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[283],"tags":[],"class_list":["post-2666","post","type-post","status-publish","format-standard","hentry","category-events-list-1"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IX Reuni\u00f3n Nacional de Di\u00e1lisis Peritoneal - SGAN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sgan.es\/gl\/events-list-1\/ix-reunion-nacional-de-dialisis-peritoneal\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IX Reuni\u00f3n Nacional de Di\u00e1lisis Peritoneal - SGAN\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sgan.es\/gl\/events-list-1\/ix-reunion-nacional-de-dialisis-peritoneal\/\" \/>\n<meta property=\"og:site_name\" content=\"SGAN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SGAN-244493612899331\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-26T07:00:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-11-02T11:41:58+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NefroGalicia\" \/>\n<meta name=\"twitter:site\" content=\"@NefroGalicia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sgan.es\\\/events-list-1\\\/ix-reunion-nacional-de-dialisis-peritoneal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgan.es\\\/events-list-1\\\/ix-reunion-nacional-de-dialisis-peritoneal\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/sgan.es\\\/#\\\/schema\\\/person\\\/5967fb171500ff790acec4188b569039\"},\"headline\":\"IX Reuni\u00f3n Nacional de Di\u00e1lisis Peritoneal\",\"datePublished\":\"2016-10-26T07:00:05+00:00\",\"dateModified\":\"2016-11-02T11:41:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sgan.es\\\/events-list-1\\\/ix-reunion-nacional-de-dialisis-peritoneal\\\/\"},\"wordCount\":8,\"publisher\":{\"@id\":\"https:\\\/\\\/sgan.es\\\/#organization\"},\"articleSection\":[\"Agenda\"],\"inLanguage\":\"gl-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sgan.es\\\/events-list-1\\\/ix-reunion-nacional-de-dialisis-peritoneal\\\/\",\"url\":\"https:\\\/\\\/sgan.es\\\/events-list-1\\\/ix-reunion-nacional-de-dialisis-peritoneal\\\/\",\"name\":\"IX Reuni\u00f3n Nacional de Di\u00e1lisis Peritoneal - SGAN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgan.es\\\/#website\"},\"datePublished\":\"2016-10-26T07:00:05+00:00\",\"dateModified\":\"2016-11-02T11:41:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sgan.es\\\/events-list-1\\\/ix-reunion-nacional-de-dialisis-peritoneal\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sgan.es\\\/events-list-1\\\/ix-reunion-nacional-de-dialisis-peritoneal\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sgan.es\\\/events-list-1\\\/ix-reunion-nacional-de-dialisis-peritoneal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/sgan.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IX Reuni\u00f3n Nacional de Di\u00e1lisis Peritoneal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sgan.es\\\/#website\",\"url\":\"https:\\\/\\\/sgan.es\\\/\",\"name\":\"SGAN\",\"description\":\"Sociedad Gallega de Nefrolog\u00eda\",\"publisher\":{\"@id\":\"https:\\\/\\\/sgan.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sgan.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sgan.es\\\/#organization\",\"name\":\"SGAN\",\"url\":\"https:\\\/\\\/sgan.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/sgan.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sgan.es\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logoSgan.jpg\",\"contentUrl\":\"https:\\\/\\\/sgan.es\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logoSgan.jpg\",\"width\":255,\"height\":193,\"caption\":\"SGAN\"},\"image\":{\"@id\":\"https:\\\/\\\/sgan.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SGAN-244493612899331\\\/\",\"https:\\\/\\\/x.com\\\/NefroGalicia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sgan.es\\\/#\\\/schema\\\/person\\\/5967fb171500ff790acec4188b569039\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90f0bb4cfb230a83119eb249ada0f109602add5ddb353f733d1ff27b8430c840?s=96&d=wp_user_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90f0bb4cfb230a83119eb249ada0f109602add5ddb353f733d1ff27b8430c840?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90f0bb4cfb230a83119eb249ada0f109602add5ddb353f733d1ff27b8430c840?s=96&d=wp_user_avatar&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/sgan.es\\\/gl\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IX Reuni\u00f3n Nacional de Di\u00e1lisis Peritoneal - SGAN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sgan.es\/gl\/events-list-1\/ix-reunion-nacional-de-dialisis-peritoneal\/","og_locale":"gl_ES","og_type":"article","og_title":"IX Reuni\u00f3n Nacional de Di\u00e1lisis Peritoneal - SGAN","og_url":"https:\/\/sgan.es\/gl\/events-list-1\/ix-reunion-nacional-de-dialisis-peritoneal\/","og_site_name":"SGAN","article_publisher":"https:\/\/www.facebook.com\/SGAN-244493612899331\/","article_published_time":"2016-10-26T07:00:05+00:00","article_modified_time":"2016-11-02T11:41:58+00:00","author":"admin","twitter_card":"summary_large_image","twitter_creator":"@NefroGalicia","twitter_site":"@NefroGalicia","twitter_misc":{"Escrito por":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sgan.es\/events-list-1\/ix-reunion-nacional-de-dialisis-peritoneal\/#article","isPartOf":{"@id":"https:\/\/sgan.es\/events-list-1\/ix-reunion-nacional-de-dialisis-peritoneal\/"},"author":{"name":"admin","@id":"https:\/\/sgan.es\/#\/schema\/person\/5967fb171500ff790acec4188b569039"},"headline":"IX Reuni\u00f3n Nacional de Di\u00e1lisis Peritoneal","datePublished":"2016-10-26T07:00:05+00:00","dateModified":"2016-11-02T11:41:58+00:00","mainEntityOfPage":{"@id":"https:\/\/sgan.es\/events-list-1\/ix-reunion-nacional-de-dialisis-peritoneal\/"},"wordCount":8,"publisher":{"@id":"https:\/\/sgan.es\/#organization"},"articleSection":["Agenda"],"inLanguage":"gl-ES"},{"@type":"WebPage","@id":"https:\/\/sgan.es\/events-list-1\/ix-reunion-nacional-de-dialisis-peritoneal\/","url":"https:\/\/sgan.es\/events-list-1\/ix-reunion-nacional-de-dialisis-peritoneal\/","name":"IX Reuni\u00f3n Nacional de Di\u00e1lisis Peritoneal - SGAN","isPartOf":{"@id":"https:\/\/sgan.es\/#website"},"datePublished":"2016-10-26T07:00:05+00:00","dateModified":"2016-11-02T11:41:58+00:00","breadcrumb":{"@id":"https:\/\/sgan.es\/events-list-1\/ix-reunion-nacional-de-dialisis-peritoneal\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sgan.es\/events-list-1\/ix-reunion-nacional-de-dialisis-peritoneal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sgan.es\/events-list-1\/ix-reunion-nacional-de-dialisis-peritoneal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/sgan.es\/"},{"@type":"ListItem","position":2,"name":"IX Reuni\u00f3n Nacional de Di\u00e1lisis Peritoneal"}]},{"@type":"WebSite","@id":"https:\/\/sgan.es\/#website","url":"https:\/\/sgan.es\/","name":"SGAN","description":"Sociedad Gallega de Nefrolog\u00eda","publisher":{"@id":"https:\/\/sgan.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sgan.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Organization","@id":"https:\/\/sgan.es\/#organization","name":"SGAN","url":"https:\/\/sgan.es\/","logo":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/sgan.es\/#\/schema\/logo\/image\/","url":"https:\/\/sgan.es\/wp-content\/uploads\/2023\/04\/logoSgan.jpg","contentUrl":"https:\/\/sgan.es\/wp-content\/uploads\/2023\/04\/logoSgan.jpg","width":255,"height":193,"caption":"SGAN"},"image":{"@id":"https:\/\/sgan.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SGAN-244493612899331\/","https:\/\/x.com\/NefroGalicia"]},{"@type":"Person","@id":"https:\/\/sgan.es\/#\/schema\/person\/5967fb171500ff790acec4188b569039","name":"admin","image":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/90f0bb4cfb230a83119eb249ada0f109602add5ddb353f733d1ff27b8430c840?s=96&d=wp_user_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/90f0bb4cfb230a83119eb249ada0f109602add5ddb353f733d1ff27b8430c840?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/90f0bb4cfb230a83119eb249ada0f109602add5ddb353f733d1ff27b8430c840?s=96&d=wp_user_avatar&r=g","caption":"admin"},"url":"https:\/\/sgan.es\/gl\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sgan.es\/gl\/wp-json\/wp\/v2\/posts\/2666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgan.es\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sgan.es\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sgan.es\/gl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sgan.es\/gl\/wp-json\/wp\/v2\/comments?post=2666"}],"version-history":[{"count":0,"href":"https:\/\/sgan.es\/gl\/wp-json\/wp\/v2\/posts\/2666\/revisions"}],"wp:attachment":[{"href":"https:\/\/sgan.es\/gl\/wp-json\/wp\/v2\/media?parent=2666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sgan.es\/gl\/wp-json\/wp\/v2\/categories?post=2666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sgan.es\/gl\/wp-json\/wp\/v2\/tags?post=2666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}